{"id":5181,"date":"2021-09-08T23:27:32","date_gmt":"2021-09-08T15:27:32","guid":{"rendered":"https:\/\/www.mairsturnstile-online.com\/product\/cancello-tornello-a-battente-sottile-mt343-esterno-e-interno\/"},"modified":"2026-05-18T17:27:34","modified_gmt":"2026-05-18T09:27:34","slug":"tornello-basculante","status":"publish","type":"product","link":"https:\/\/www.mairsturnstile-online.com\/it\/prodotto\/tornello-basculante\/","title":{"rendered":"TORNELLO A BATTENTE SLIM MT343(ESTERNO)"},"content":{"rendered":"\n        <div class=\"modelViewerBlock\" data-attributes='{&quot;model&quot;:{&quot;modelUrl&quot;:&quot;https:\\\/\\\/www.mairsturnstile-online.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/MT343-1.glb&quot;,&quot;poster&quot;:&quot;&quot;,&quot;arEnabled&quot;:false,&quot;arMode&quot;:&quot;webxr scene-viewer quick-look&quot;,&quot;arPlacement&quot;:&quot;floor&quot;,&quot;modelISOSrc&quot;:null},&quot;align&quot;:&quot;start&quot;,&quot;uniqueId&quot;:&quot;model17087&quot;,&quot;currentViewer&quot;:&quot;modelViewer&quot;,&quot;O3DVSettings&quot;:{&quot;isFullscreen&quot;:true,&quot;camera&quot;:null,&quot;mouseControl&quot;:true,&quot;zoom&quot;:true},&quot;lazyLoad&quot;:false,&quot;loading&quot;:&quot;auto&quot;,&quot;zoom&quot;:true,&quot;preload&quot;:&quot;auto&quot;,&quot;mouseControl&quot;:true,&quot;fullscreen&quot;:true,&quot;zoomInOutBtn&quot;:false,&quot;cameraBtn&quot;:false,&quot;loadingPercentage&quot;:false,&quot;progressBar&quot;:true,&quot;exposure&quot;:&quot;1&quot;,&quot;shadow&quot;:1,&quot;woo&quot;:false,&quot;placement&quot;:&quot;shortcode&quot;,&quot;styles&quot;:{&quot;width&quot;:&quot;1150px&quot;,&quot;height&quot;:&quot;700px&quot;,&quot;bgColor&quot;:&quot;#f9f9f9&quot;}}'>\n            <div class=\"bp3d_backup_view\" style=\"display: none;height:350px;\">\n                <model-viewer camera-controls src=\"https:\/\/www.mairsturnstile-online.com\/wp-content\/uploads\/2025\/08\/MT343-1.glb\" style=\"height: 350px;\"><\/model-viewer>\n            <\/div>\n        <\/div>\n\n        \n<p>Elegante tornello a battente sottile MT343 (PER ESTERNI E INTERNI), design architettonico per hall moderne. Valorizzate l&#8217;ingresso del vostro edificio con tornelli a battente dal design elegante, caratterizzati da sottili casse in acciaio inox a forma di V, barriere a battente in vetro temperato e illuminazione a LED personalizzabile. I nostri esclusivi tornelli a battente architettonici combinano un accesso ad alta sicurezza con un&#8217;estetica sofisticata, ideali per sedi aziendali e spazi commerciali di lusso. Scoprite i tornelli a battente di alta gamma con un design elegante e moderno e un sistema avanzato di rilevamento anti-accesso non autorizzato. I nostri tornelli a battente di fascia alta offrono un flusso rapido (30-40 persone\/min), un funzionamento silenzioso e fluido e una perfetta integrazione con i sistemi di controllo accessi. Perfetti per hall aziendali, uffici e strutture di alto livello.    <\/p>\n<p>Possiamo fornire servizi OEM e ODM. Tornello a battente personalizzato, produttore OEM\/ODM con prezzi di fabbrica. Personalizza il tuo tornello a battente con larghezze di corsia regolabili (550\u20131200 mm), diverse finiture del cabinet, pannelli in vetro temperato o acrilico e configurazioni LED RGB. Servizi OEM\/ODM disponibili. Il nostro tornello a battente si adatta a qualsiasi esigenza di sicurezza e stile architettonico. Certificato ISO\/CE\/FCC. Contatta il nostro team di ingegneri per soluzioni personalizzate. Massimizza il flusso pedonale con un tornello a battente ad alta capacit\u00e0, caratterizzato da una velocit\u00e0 di apertura di 0,5\u20130,8 secondi e una capacit\u00e0 di 30\u201340 persone\/minuto (fino a 60 con modalit\u00e0 memoria). Il nostro tornello a battente veloce riduce la congestione nelle ore di punta, mantenendo al contempo un&#8217;elevata sicurezza e un design elegante. Ideale per stadi, centri congressi, snodi di trasporto e campus aziendali.       <\/p>\n<p>Abbiamo designer esperti in grado di completare una profonda personalizzazione in base alle vostre esigenze. Forniremo una serie di materiali come rendering 3D, disegni dimensionali, ecc. nel pi\u00f9 breve tempo possibile.  Protect your facility with high-security swing turnstile featuring multi-point infrared sensor arrays (6\u20138 pairs), real-time tailgating detection, audible alarms, and anti-climb design. Our swing turnstile prevents unauthorized entry while maintaining elegant appearance. Ideal for government, data centers, airports, banks, and corporate facilities  <\/p>\n<p>Swing Turnstile for Corporate Offices, Secure &#038; Stylish Lobby Entrance, Secure your corporate headquarters with a sleek swing turnstile designed for seamless employee flow and modern aesthetics. Our swing turnstile integrates with biometric, RFID, and facial recognition systems, offering ADA-compliant wide lanes (up to 900mm). Perfect for office lobbies, elevator banks, and employee entrances. Ensure ADA compliance with our swing turnstile featuring adjustable wide lanes (550\u20131200mm) for wheelchairs, strollers, luggage, and bicycles. Our accessible swing turnstile offers fail-open emergency mode, integrates with biometric access control, and meets fire safety codes. ISO\/CE\/FCC certified.     <\/p>\n<p>Tutti i nostri prodotti sono coperti da una garanzia di due anni e da un supporto duraturo per la manutenzione e le riparazioni. Forniamo anche dispositivi biometrici, come scanner di impronte digitali e fotocamere per il riconoscimento facciale. Lettore di schede RFID, scanner di codici QR. Se hai bisogno di integrare questi dispositivi sul tornello a battente o hai qualsiasi domanda, <a href=\"https:\/\/www.mairsturnstile-online.com\/contact-us\/\">richiedi un preventivo.<\/a> Heavy-Duty Swing Turnstile, Premium Quality 304 Stainless Steel, Engineered for longevity\u2014our heavy-duty swing turnstile features 1.5mm 304 stainless steel housing, industrial-grade brushless servo motor, and 5+ million cycle lifespan. High-quality swing turnstile with premium materials ensures maintenance-free performance for years. ISO, CE &#038; FCC certified. Get factory-direct pricing.   <\/p>\n<p>Possiamo anche creare per te un rendering in pochi minuti in base al tuo scenario reale. Forniamo anche layout e disegni dettagliati, nonch\u00e9 disegni di installazione. Non preoccuparti dell&#8217;installazione. Si prega di scaricare il nostro file PDF corrispondente per dimensioni specifiche e dimensioni di installazione.  <\/p>\n\n\t\t\t\n\t<style type=\"text\/css\">\n\t\t.slider-info-17098.bafg-slider-info .bafg-slider-title {\n\t\t\t\t\t\t\tfont-size:\n\t\t\t\t\t22px\t\t\t\t;\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\n\t\t.slider-info-17098.bafg-slider-info .bafg-slider-description {\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\t\t\n\t\t\n\t\t.slider-info-17098.bafg-slider-info .bafg_slider_readmore_button {\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\ttext-align: center;\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\n\t\t.slider-info-17098.bafg-slider-info .bafg_slider_readmore_button:hover {\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\t<\/style>\n\t\n\t\t\t<div class=\"bafg-twentytwenty-container slider-17098  \"\n\t\t\t\tbafg-orientation=\"horizontal\" bafg-default-offset=\"0.5\"\n\t\t\t\tbafg-before-label=\"Before\"\n\t\t\t\tbafg-after-label=\"After\" bafg-overlay=\"1\"\n\t\t\t\tbafg-move-slider-on-hover=\"1\"\n\t\t\t\tbafg-click-to-move=\"\">\n\n\t\t\t\t\t\t\t\t<img class=\"skip-lazy\" data-skip-lazy\t\t\t\t\tsrc=\"https:\/\/www.mairsturnstile-online.com\/wp-content\/uploads\/2025\/08\/outdoor-turnstile-8.jpg\" alt=\"\">\n\t\t\t\t<img class=\"skip-lazy\" data-skip-lazy\t\t\t\t\tsrc=\"https:\/\/www.mairsturnstile-online.com\/wp-content\/uploads\/2021\/09\/outdoor-turnstile-7.jpg\" alt=\"\">\n\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"bafg-slider-info-wraper\">\n\t\t<div style=\"\" class=\"slider-info-17098 bafg-slider-info\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\n<p><strong>Technical Parameter:<\/strong><\/p>\n<p>1. Dimensioni: 1400*180*1000 mm (pu\u00f2 essere personalizzato)<br \/>\n2. Larghezza corsia: 600 mm (Standard) 900 mm (Disabili)<br \/>\n3. Materiale del braccio: acrilico<br \/>\n4. Velocit\u00e0 di passaggio: 40 persone\/minuto<br \/>\n5. Alimentazione: 110 V\/220 V 50\/60 Hz<br \/>\n6. Motore senza spazzole<br \/>\n7. Segnale cancello aperto: contatto pulito\/rel\u00e8<br \/>\n8. Motore di azionamento: 24 V<br \/>\n9. Peso: 70 kg\/pz<br \/>\n10. Le dimensioni e lo spessore del materiale possono essere personalizzati<br \/>\n11. Casing Material: 304 stainless steel<br \/>\n12. Affidabilit\u00e0 del meccanismo: 3 milioni-5 milioni, senza colpa<br \/>\n13. Luci a LED sui bracci opzionali<br \/>\n14. LED sul pannello laterale opzionali<br \/>\n15. Spessore del braccio oscillante: 10 mm<br \/>\n16. Direzione di funzionamento: bidirezionale\/monodirezionale<br \/>\n17. Situazione di emergenza: apertura automatica in caso di interruzione di corrente tramite condensatore.<br \/>\n18. Umidit\u00e0 del tornello girevole: \u226490%<br \/>\n19. Temperatura di lavoro: -20\u2103~60\u2103<br \/>\n20. Distanza di comunicazione: \u22641200 m<br \/>\n21. Interfaccia di comunicazione: RS485<br \/>\n22. Caratteristica: lettore IC\/ID, lettore di codici a barre, riconoscimento facciale, impronte digitali, altre apparecchiature di controllo accessi, UPS, ecc.<br \/>\n23. Tempo necessario per l&#8217;apertura: 0,2 s<br \/>\n24. Ambiente di lavoro: all&#8217;interno o all&#8217;esterno (l&#8217;esterno \u00e8 facoltativo)<br \/>\n25. Campo di applicazione: comunit\u00e0, fabbrica, cantiere, scuola, luogo del resort, ecc<\/p>\n<p>Possiamo fornire l&#8217;intera soluzione di controllo degli accessi e della sicurezza. If you have your own access control system, you can directly use our turnstile gate. Se non ne disponete, forniamo anche una soluzione completa per il controllo degli accessi di sicurezza. Per i dettagli, si prega di fare riferimento al video qui sotto.  <\/p>\n<p><iframe title=\"Tornello ottico a battente, Tornello a barriera girevole, Tornello a battente - MairsTurnstile\" src=\"https:\/\/www.youtube.com\/embed\/hdoBSoM85u4\" width=\"1110\" height=\"650\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expert advice, Free design, OEM Logo, Color &#038; Size Available, Global Export, Fast sample shipping, Low MOQ. Get factory direct wholesale pricing from a trusted manufacturer, Long-term cooperation support for global agents &#038; wholesalers.<span style=\"color: #fcaf3b;\"><strong><a style=\"color: #fcaf3b;\" title=\"Tornello con barriera a ribalta certificato Mairs CE\" href=\"http:\/\/mairsturnstile.com\/wp-content\/uploads\/2022\/09\/Mairs-CE-Certificate-Flap-Barrier-Turnstile.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">CE Certificated,<\/a> <a style=\"color: #fcaf3b;\" title=\"Mairs ISO9001 Certificate\" href=\"http:\/\/mairsturnstile.com\/wp-content\/uploads\/2022\/09\/Mairs-Registration-Certificate-ISO9001.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ISO9001 Certificated.<\/a><\/strong><\/span> <\/p>\n<p><a title=\"Opuscolo sui tornelli a battente\" href=\"https:\/\/mairsturnstile-online.com\/flipbook\/mt343-swing-turnstile-brochure\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignnone size-full wp-image-11034\" src=\"http:\/\/mairsturnstile.com\/wp-content\/uploads\/2022\/09\/pdf-MairsTurnstile.png\" alt=\"\" width=\"32\" height=\"32\"> <span style=\"color: #fcaf3b;\"><strong>Brochure del tornello girevole MT343<\/strong><\/span><\/a><\/p>\n","protected":false},"featured_media":61553,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[76],"product_tag":[],"class_list":["post-5181","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-tornello-a-battente"],"_links":{"self":[{"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/product\/5181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/comments?post=5181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/media\/61553"}],"wp:attachment":[{"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/media?parent=5181"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/product_cat?post=5181"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mairsturnstile-online.com\/it\/wp-json\/wp\/v2\/product_tag?post=5181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}